{"id":4049,"date":"2022-08-14T20:09:44","date_gmt":"2022-08-14T18:09:44","guid":{"rendered":"https:\/\/tablaoflamenco1911.com\/es\/?p=4049"},"modified":"2026-03-02T17:16:54","modified_gmt":"2026-03-02T16:16:54","slug":"los-tres-pasadizos-secretos","status":"publish","type":"post","link":"https:\/\/tablaoflamenco1911.com\/pt\/los-tres-pasadizos-secretos\/","title":{"rendered":"Los tres pasadizos secretos"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-pt\">Desculpe, este conte\u00fado s\u00f3 est\u00e1 dispon\u00edvel em <a href=\"https:\/\/tablaoflamenco1911.com\/es\/wp-json\/wp\/v2\/posts\/4049\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"Espa\u00f1ol\">Espa\u00f1ol<\/a>, <a href=\"https:\/\/tablaoflamenco1911.com\/en\/wp-json\/wp\/v2\/posts\/4049\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">English<\/a> e <a href=\"https:\/\/tablaoflamenco1911.com\/fr\/wp-json\/wp\/v2\/posts\/4049\" class=\"qtranxs-available-language-link qtranxs-available-language-link-fr\" title=\"Fran\u00e7ais\">Fran\u00e7ais<\/a>.<\/p><p>Como dir\u00edan en los cuentos de princesas y pr\u00edncipes, cuenta la leyenda que el rey Alfonso XIII acced\u00eda al Tablao por los pasadizos que comunicaban los reservados del s\u00f3tano del tablao y el Palacio Real para no ser visto abiertamente por el pueblo.<\/p>\n<p>Si abrimos la puerta que da acceso a ese pasadizo podemos ver que hab\u00eda acceso tres galer\u00edas, aunque en la actualidad est\u00e1n tapiadas completamente, excepto la del Palacio, que dispone de una peque\u00f1a puerta por la que apenas cabe una persona. Incre\u00edble \u00bfverdad?<\/p>\n<p>Otro llevaba a la <strong>Plaza de Neptuno<\/strong>\u00a0donde podemos encontrar los hist\u00f3ricos hoteles de lujo\u00a0<strong>Palace<\/strong>\u00a0y\u00a0<strong>Ritz <\/strong>y por los que imaginamos avanzar a &#8220;los se\u00f1oritos&#8221; ocultos de las miradas indiscretas.<\/p>\n<p>El tercero, ya tapiado, no se sabe exactamente a d\u00f3nde se dirige.<\/p>\n<p>C\u00f3mo veis, a\u00fan quedan muchos secretos que descubrir y nuevas an\u00e9cdotas que crear en el <strong>Tablao Flamenco 1911<\/strong>, la Catedral del Flamenco en Madrid<\/p>","protected":false},"excerpt":{"rendered":"Desculpe, este conte\u00fado s\u00f3 est\u00e1 dispon\u00edvel em Espa\u00f1ol, English e Fran\u00e7ais.Como dir\u00edan en los cuentos de princesas y pr\u00edncipes, cuenta la leyenda que el rey Alfonso XIII acced\u00eda al Tablao por los pasadizos que comunicaban los reservados del s\u00f3tano del tablao y el Palacio Real para no ser visto abiertamente por el pueblo. Si abrimos&#8230;","protected":false},"author":2,"featured_media":4054,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-4049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tablao-flamenco-1911"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los tres pasadizos secretos - Tablao Flamenco 1911<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los tres pasadizos secretos - Tablao Flamenco 1911\" \/>\n<meta property=\"og:description\" content=\"Desculpe, este conte\u00fado s\u00f3 est\u00e1 dispon\u00edvel em Espa\u00f1ol, English e Fran\u00e7ais.Como dir\u00edan en los cuentos de princesas y pr\u00edncipes, cuenta la leyenda que el rey Alfonso XIII acced\u00eda al Tablao por los pasadizos que comunicaban los reservados del s\u00f3tano del tablao y el Palacio Real para no ser visto abiertamente por el pueblo. Si abrimos...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tablaoflamenco1911.com\/pt\/los-tres-pasadizos-secretos\/\" \/>\n<meta property=\"og:site_name\" content=\"Tablao Flamenco 1911\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-14T18:09:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-02T16:16:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tablaoflamenco1911.com\/wp-content\/uploads\/2022\/08\/pasadizo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"876\" \/>\n\t<meta property=\"og:image:height\" content=\"491\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cristina Folgueira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cristina Folgueira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/los-tres-pasadizos-secretos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/los-tres-pasadizos-secretos\\\/\"},\"author\":{\"name\":\"Cristina Folgueira\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/#\\\/schema\\\/person\\\/58a15a03bd6b7dfcfdab6f4724c78a7a\"},\"headline\":\"Los tres pasadizos secretos\",\"datePublished\":\"2022-08-14T18:09:44+00:00\",\"dateModified\":\"2026-03-02T16:16:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/los-tres-pasadizos-secretos\\\/\"},\"wordCount\":537,\"image\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/los-tres-pasadizos-secretos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pasadizo.jpg\",\"articleSection\":[\"Tablao Flamenco 1911\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/pt\\\/los-tres-pasadizos-secretos\\\/\",\"url\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/pt\\\/los-tres-pasadizos-secretos\\\/\",\"name\":\"Los tres pasadizos secretos - Tablao Flamenco 1911\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/pt\\\/los-tres-pasadizos-secretos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/los-tres-pasadizos-secretos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pasadizo.jpg\",\"datePublished\":\"2022-08-14T18:09:44+00:00\",\"dateModified\":\"2026-03-02T16:16:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/#\\\/schema\\\/person\\\/58a15a03bd6b7dfcfdab6f4724c78a7a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/pt\\\/los-tres-pasadizos-secretos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/tablaoflamenco1911.com\\\/pt\\\/los-tres-pasadizos-secretos\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/pt\\\/los-tres-pasadizos-secretos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pasadizo.jpg\",\"contentUrl\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pasadizo.jpg\",\"width\":876,\"height\":491},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/pt\\\/los-tres-pasadizos-secretos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los tres pasadizos secretos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/pt\\\/\",\"name\":\"Tablao Flamenco 1911\",\"description\":\"La Catedral del Flamenco en Madrid\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/#\\\/schema\\\/person\\\/58a15a03bd6b7dfcfdab6f4724c78a7a\",\"name\":\"Cristina Folgueira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/affd104d604a5c3a451339e8b978de80710b9ae81e5bdfb448944dc3101edb29?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/affd104d604a5c3a451339e8b978de80710b9ae81e5bdfb448944dc3101edb29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/affd104d604a5c3a451339e8b978de80710b9ae81e5bdfb448944dc3101edb29?s=96&d=mm&r=g\",\"caption\":\"Cristina Folgueira\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los tres pasadizos secretos - Tablao Flamenco 1911","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/","og_locale":"pt_PT","og_type":"article","og_title":"Los tres pasadizos secretos - Tablao Flamenco 1911","og_description":"Desculpe, este conte\u00fado s\u00f3 est\u00e1 dispon\u00edvel em Espa\u00f1ol, English e Fran\u00e7ais.Como dir\u00edan en los cuentos de princesas y pr\u00edncipes, cuenta la leyenda que el rey Alfonso XIII acced\u00eda al Tablao por los pasadizos que comunicaban los reservados del s\u00f3tano del tablao y el Palacio Real para no ser visto abiertamente por el pueblo. Si abrimos...","og_url":"https:\/\/tablaoflamenco1911.com\/pt\/los-tres-pasadizos-secretos\/","og_site_name":"Tablao Flamenco 1911","article_published_time":"2022-08-14T18:09:44+00:00","article_modified_time":"2026-03-02T16:16:54+00:00","og_image":[{"width":876,"height":491,"url":"https:\/\/tablaoflamenco1911.com\/wp-content\/uploads\/2022\/08\/pasadizo.jpg","type":"image\/jpeg"}],"author":"Cristina Folgueira","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Cristina Folgueira","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tablaoflamenco1911.com\/es\/los-tres-pasadizos-secretos\/#article","isPartOf":{"@id":"https:\/\/tablaoflamenco1911.com\/es\/los-tres-pasadizos-secretos\/"},"author":{"name":"Cristina Folgueira","@id":"https:\/\/tablaoflamenco1911.com\/es\/#\/schema\/person\/58a15a03bd6b7dfcfdab6f4724c78a7a"},"headline":"Los tres pasadizos secretos","datePublished":"2022-08-14T18:09:44+00:00","dateModified":"2026-03-02T16:16:54+00:00","mainEntityOfPage":{"@id":"https:\/\/tablaoflamenco1911.com\/es\/los-tres-pasadizos-secretos\/"},"wordCount":537,"image":{"@id":"https:\/\/tablaoflamenco1911.com\/es\/los-tres-pasadizos-secretos\/#primaryimage"},"thumbnailUrl":"https:\/\/tablaoflamenco1911.com\/wp-content\/uploads\/2022\/08\/pasadizo.jpg","articleSection":["Tablao Flamenco 1911"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/tablaoflamenco1911.com\/pt\/los-tres-pasadizos-secretos\/","url":"https:\/\/tablaoflamenco1911.com\/pt\/los-tres-pasadizos-secretos\/","name":"Los tres pasadizos secretos - Tablao Flamenco 1911","isPartOf":{"@id":"https:\/\/tablaoflamenco1911.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tablaoflamenco1911.com\/pt\/los-tres-pasadizos-secretos\/#primaryimage"},"image":{"@id":"https:\/\/tablaoflamenco1911.com\/es\/los-tres-pasadizos-secretos\/#primaryimage"},"thumbnailUrl":"https:\/\/tablaoflamenco1911.com\/wp-content\/uploads\/2022\/08\/pasadizo.jpg","datePublished":"2022-08-14T18:09:44+00:00","dateModified":"2026-03-02T16:16:54+00:00","author":{"@id":"https:\/\/tablaoflamenco1911.com\/es\/#\/schema\/person\/58a15a03bd6b7dfcfdab6f4724c78a7a"},"breadcrumb":{"@id":"https:\/\/tablaoflamenco1911.com\/pt\/los-tres-pasadizos-secretos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/tablaoflamenco1911.com\/pt\/los-tres-pasadizos-secretos\/"]]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/tablaoflamenco1911.com\/pt\/los-tres-pasadizos-secretos\/#primaryimage","url":"https:\/\/tablaoflamenco1911.com\/wp-content\/uploads\/2022\/08\/pasadizo.jpg","contentUrl":"https:\/\/tablaoflamenco1911.com\/wp-content\/uploads\/2022\/08\/pasadizo.jpg","width":876,"height":491},{"@type":"BreadcrumbList","@id":"https:\/\/tablaoflamenco1911.com\/pt\/los-tres-pasadizos-secretos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tablaoflamenco1911.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Los tres pasadizos secretos"}]},{"@type":"WebSite","@id":"https:\/\/tablaoflamenco1911.com\/pt\/#website","url":"https:\/\/tablaoflamenco1911.com\/pt\/","name":"Tablao Flamenco 1911","description":"La Catedral del Flamenco en Madrid","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tablaoflamenco1911.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/tablaoflamenco1911.com\/es\/#\/schema\/person\/58a15a03bd6b7dfcfdab6f4724c78a7a","name":"Cristina Folgueira","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/affd104d604a5c3a451339e8b978de80710b9ae81e5bdfb448944dc3101edb29?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/affd104d604a5c3a451339e8b978de80710b9ae81e5bdfb448944dc3101edb29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/affd104d604a5c3a451339e8b978de80710b9ae81e5bdfb448944dc3101edb29?s=96&d=mm&r=g","caption":"Cristina Folgueira"}}]}},"_links":{"self":[{"href":"https:\/\/tablaoflamenco1911.com\/pt\/wp-json\/wp\/v2\/posts\/4049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tablaoflamenco1911.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tablaoflamenco1911.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tablaoflamenco1911.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tablaoflamenco1911.com\/pt\/wp-json\/wp\/v2\/comments?post=4049"}],"version-history":[{"count":5,"href":"https:\/\/tablaoflamenco1911.com\/pt\/wp-json\/wp\/v2\/posts\/4049\/revisions"}],"predecessor-version":[{"id":27577,"href":"https:\/\/tablaoflamenco1911.com\/pt\/wp-json\/wp\/v2\/posts\/4049\/revisions\/27577"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tablaoflamenco1911.com\/pt\/wp-json\/wp\/v2\/media\/4054"}],"wp:attachment":[{"href":"https:\/\/tablaoflamenco1911.com\/pt\/wp-json\/wp\/v2\/media?parent=4049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tablaoflamenco1911.com\/pt\/wp-json\/wp\/v2\/categories?post=4049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tablaoflamenco1911.com\/pt\/wp-json\/wp\/v2\/tags?post=4049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}