{"id":54979,"date":"2026-03-31T20:56:24","date_gmt":"2026-03-31T18:56:24","guid":{"rendered":"https:\/\/tablaoflamenco1911.com\/es\/?p=54979"},"modified":"2026-03-31T21:17:57","modified_gmt":"2026-03-31T19:17:57","slug":"las-sevillanas-son-realmente-un-palo-flamenco","status":"publish","type":"post","link":"https:\/\/tablaoflamenco1911.com\/de\/sind-sevillanas-ein-flamenco-stil\/","title":{"rendered":"Die Sevillanas: Sind sie wirklich ein Flamenco-Stil?"},"content":{"rendered":"<p><\/p>\n<p data-path-to-node=\"28\">Es ist die Musik, die die Jahrm\u00e4rkte \u00fcberflutet, der Tanz, der Generationen verbindet, und der Soundtrack jeder Feier im S\u00fcden Spaniens. Es gibt jedoch eine ewige Debatte zwischen Puristen und Liebhabern: Sind die Sevillanas wirklich ein Flamenco-Stil oder einfach nur popul\u00e4re Folklore?<\/p>\n<p data-path-to-node=\"29\">Um diesen Zweifel zu l\u00f6sen, m\u00fcssen wir auf die Geschichte blicken. Obwohl sie heute innerhalb der Flamenco-Kultur studiert werden, ist ihr Ursprung rein folkloristisch. Die Sevillanas stammen von der alten Seguidilla aus La Mancha ab, die bei ihrer Ankunft in Sevilla von der Anmut, dem Takt und dem \u201eFlair\u201c Niederandalusiens durchdrungen wurde. Im Laufe der Jahrhunderte wurde dieser Tanz immer mehr \u201eflamenco-isiert\u201c, bis er zu einer unverzichtbaren Disziplin in jedem Tablao wurde.<\/p>\n<h2 data-path-to-node=\"30\">Was sind Flamenco-Sevillanas?<\/h2>\n<p data-path-to-node=\"31\">Flamenco-Sevillanas sind die k\u00fcnstlerische Entwicklung dieser popul\u00e4ren Folklore. Als professionelle K\u00fcnstler begannen, sie zu interpretieren, brachten sie eine verfeinerte Technik, einen komplexeren Zapateado und vor allem jenes tiefe Gef\u00fchl ein, das wir Quej\u00edo nennen.<\/p>\n<p data-path-to-node=\"32\">Im Gegensatz zu der Version, die auf Jahrm\u00e4rkten getanzt wird, ist die Flamenco-Sevillana schlicht, technisch und von einer imposanten visuellen Sch\u00f6nheit. Hier verschwimmt die Linie zwischen Gesellschaftstanz und professioneller Kunst, sodass die Sevillanas vom gro\u00dfen Publikum ohne Zweifel als Flamenco akzeptiert werden.<\/p>\n<h2 data-path-to-node=\"33\">Unterschied zwischen Flamenco und Sevillanas<\/h2>\n<p data-path-to-node=\"34\">Obwohl sie \u00c4sthetik und Kost\u00fcme teilen, liegt der Unterschied haupts\u00e4chlich in ihrer mathematischen Struktur:<\/p>\n<ul data-path-to-node=\"35\">\n<li>\n<p data-path-to-node=\"35,0,0\"><b data-path-to-node=\"35,0,0\" data-index-in-node=\"0\">Feste Struktur:<\/b> Die Sevillanas haben einen 3\/4-Takt und eine unverr\u00fcckbare Struktur aus vier Strophen (Coplas). Man wei\u00df immer genau, wann sie beginnen und wann sie enden.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"35,1,0\"><b data-path-to-node=\"35,1,0\" data-index-in-node=\"0\">Improvisation:<\/b> In einem traditionellen <a class=\"ng-star-inserted\" href=\"https:\/\/tablaoflamenco1911.com\/de\/flamenco-palos\/\" target=\"_blank\" rel=\"noopener\">Flamenco-Stil<\/a> sind Improvisation und die organische Kommunikation zwischen Gesang und Tanz die Basis. Da Sevillanas ein Paartanz sind, erfordern sie das Befolgen vorgegebener Schritte.<\/p>\n<\/li>\n<\/ul>\n<h2 data-path-to-node=\"36\">Warum werden die Sevillanas mit dem Flamenco assoziiert?<\/h2>\n<p data-path-to-node=\"37\">Die Assoziation ergibt sich ganz nat\u00fcrlich aus dem Kontext und der Inszenierung. Sie werden auf der spanischen Gitarre gespielt, mit gebrochenen Stimmen gesungen und im ikonischen Flamenco-Kleid getanzt.<\/p>\n<p data-path-to-node=\"38\">Die gro\u00dfen Gestalten der Geschichte haben die Sevillanas in die Kategorie der bedeutenden Kunst erhoben und die Vorstellung gefestigt, dass sie ein grundlegendes Element der Flamenco-Imagin\u00e4rwelt sind.<\/p>\n<h2 data-path-to-node=\"39\">Sevillanas-Unterricht: Wie sie strukturiert sind<\/h2>\n<p data-path-to-node=\"40\">Wenn Sie nach den Arten von Sevillanas-Unterricht suchen, die es gibt, werden Sie als Erstes lernen, dass es nicht nur ein Tanz ist, sondern eine Verf\u00fchrungsgeschichte, die in vier Akten erz\u00e4hlt wird. Jede der Coplas stellt eine andere Phase der Beziehung zwischen dem Paar dar.<\/p>\n<h3 data-path-to-node=\"41\">Die vier traditionellen Sevillanas<\/h3>\n<ol start=\"1\" data-path-to-node=\"42\">\n<li>\n<p data-path-to-node=\"42,0,0\"><b data-path-to-node=\"42,0,0\" data-index-in-node=\"0\">Die Begegnung:<\/b> Die erste Ann\u00e4herung, der Blickkontakt und das Flirten.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"42,1,0\"><b data-path-to-node=\"42,1,0\" data-index-in-node=\"0\">Die Verf\u00fchrung:<\/b> Die k\u00f6rperliche Ann\u00e4herung und das Spiel der Arme, das das Interesse signalisiert.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"42,2,0\"><b data-path-to-node=\"42,2,0\" data-index-in-node=\"0\">Der Streit:<\/b> Die Distanzierung und der vorget\u00e4uschte \u00c4rger, der Spannung erzeugt.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"42,3,0\"><b data-path-to-node=\"42,3,0\" data-index-in-node=\"0\">Die Vers\u00f6hnung:<\/b> Das Happy End, bei dem das Paar in Harmonie endet.<\/p>\n<\/li>\n<\/ol>\n<p data-path-to-node=\"43\">Diese heilige Struktur erlaubt es zwei Fremden, an jedem Ort der Welt zusammen zu tanzen, indem sie demselben Code folgen.<\/p>\n<h2 data-path-to-node=\"44\">Die Sevillanas im Kontext des aktuellen Flamenco<\/h2>\n<p data-path-to-node=\"45\">Heutzutage sind die Sevillanas f\u00fcr viele, die sich dieser Kunst n\u00e4hern wollen, weiterhin das Eingangstor. Obwohl sie technisch gesehen als \u201eflamenco-isierte\u201c Folklore gelten, spricht ihre Pr\u00e4senz auf den B\u00fchnen f\u00fcr ihre G\u00fcltigkeit und eine Eleganz, die keine Etiketten kennt.<\/p>\n<p data-path-to-node=\"46\">Wer einen Schritt weiter gehen und in das Wesen von Gesang und Tanz eintauchen m\u00f6chte, findet in Madrid Angebote, bei denen die tiefsten Stile mit Authentizit\u00e4t und Respekt vor der Tradition ausgedr\u00fcckt werden. Wenn Sie suchen, <a class=\"ng-star-inserted\" href=\"https:\/\/tablaoflamenco1911.com\/de\/\" target=\"_blank\" rel=\"noopener\">wo man in Madrid Flamenco sehen kann<\/a>, lohnt es sich, Orte zu entdecken, an denen diese Wurzel noch kr\u00e4ftig schl\u00e4gt.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"Es ist die Musik, die die Jahrm\u00e4rkte \u00fcberflutet, der Tanz, der Generationen verbindet, und der Soundtrack jeder Feier im S\u00fcden Spaniens. Es gibt jedoch eine ewige Debatte zwischen Puristen und Liebhabern: Sind die Sevillanas wirklich ein Flamenco-Stil oder einfach nur popul\u00e4re Folklore? Um diesen Zweifel zu l\u00f6sen, m\u00fcssen wir auf die Geschichte blicken. Obwohl sie&#8230;","protected":false},"author":8,"featured_media":54980,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-54979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-flamenca"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sevillanas Flamenco-Stil: Sind sie Flamenco und welche Arten gibt es?<\/title>\n<meta name=\"description\" content=\"Erfahren Sie, ob Sevillanas ein Flamenco-Stil sind, ihre Unterschiede zum Flamenco und die Arten von Sevillanas. Leitfaden zu Herkunft und Struktur.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sevillanas Flamenco-Stil: Sind sie Flamenco und welche Arten gibt es?\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie, ob Sevillanas ein Flamenco-Stil sind, ihre Unterschiede zum Flamenco und die Arten von Sevillanas. Leitfaden zu Herkunft und Struktur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tablaoflamenco1911.com\/de\/son-las-sevillanas-un-palo-flamenco\/\" \/>\n<meta property=\"og:site_name\" content=\"Tablao Flamenco 1911\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-31T18:56:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-31T19:17:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tablaoflamenco1911.com\/wp-content\/uploads\/2026\/03\/claudia-de-utrera-7511-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Miguel Blanco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miguel Blanco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/son-las-sevillanas-un-palo-flamenco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/son-las-sevillanas-un-palo-flamenco\\\/\"},\"author\":{\"name\":\"Miguel Blanco\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/#\\\/schema\\\/person\\\/5c9c054f5ed0de8157b146ce7171d5e7\"},\"headline\":\"Die Sevillanas: Sind sie wirklich ein Flamenco-Stil?\",\"datePublished\":\"2026-03-31T18:56:24+00:00\",\"dateModified\":\"2026-03-31T19:17:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/son-las-sevillanas-un-palo-flamenco\\\/\"},\"wordCount\":6886,\"image\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/son-las-sevillanas-un-palo-flamenco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/claudia-de-utrera-7511-scaled.webp\",\"articleSection\":[\"Cultura Flamenca\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/son-las-sevillanas-un-palo-flamenco\\\/\",\"url\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/son-las-sevillanas-un-palo-flamenco\\\/\",\"name\":\"Sevillanas Flamenco-Stil: Sind sie Flamenco und welche Arten gibt es?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/son-las-sevillanas-un-palo-flamenco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/son-las-sevillanas-un-palo-flamenco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/claudia-de-utrera-7511-scaled.webp\",\"datePublished\":\"2026-03-31T18:56:24+00:00\",\"dateModified\":\"2026-03-31T19:17:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/#\\\/schema\\\/person\\\/5c9c054f5ed0de8157b146ce7171d5e7\"},\"description\":\"Erfahren Sie, ob Sevillanas ein Flamenco-Stil sind, ihre Unterschiede zum Flamenco und die Arten von Sevillanas. Leitfaden zu Herkunft und Struktur.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/son-las-sevillanas-un-palo-flamenco\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/son-las-sevillanas-un-palo-flamenco\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/son-las-sevillanas-un-palo-flamenco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/claudia-de-utrera-7511-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/claudia-de-utrera-7511-scaled.webp\",\"width\":2560,\"height\":1706,\"caption\":\"Bailaora de flamenco con vestido rojo de lunares en el Tablao Flamenco 1911 de Madrid, representando la est\u00e9tica de las sevillanas.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/son-las-sevillanas-un-palo-flamenco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sevillanas Flamenco-Stil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/\",\"name\":\"Tablao Flamenco 1911\",\"description\":\"La Catedral del Flamenco en Madrid\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/#\\\/schema\\\/person\\\/5c9c054f5ed0de8157b146ce7171d5e7\",\"name\":\"Miguel Blanco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/359874fd676a9bfbf3a5d62f8bb888a22a657034662dd62c3669b5e7274a1365?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/359874fd676a9bfbf3a5d62f8bb888a22a657034662dd62c3669b5e7274a1365?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/359874fd676a9bfbf3a5d62f8bb888a22a657034662dd62c3669b5e7274a1365?s=96&d=mm&r=g\",\"caption\":\"Miguel Blanco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sevillanas Flamenco-Stil: Sind sie Flamenco und welche Arten gibt es?","description":"Erfahren Sie, ob Sevillanas ein Flamenco-Stil sind, ihre Unterschiede zum Flamenco und die Arten von Sevillanas. Leitfaden zu Herkunft und Struktur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/","og_locale":"de_DE","og_type":"article","og_title":"Sevillanas Flamenco-Stil: Sind sie Flamenco und welche Arten gibt es?","og_description":"Erfahren Sie, ob Sevillanas ein Flamenco-Stil sind, ihre Unterschiede zum Flamenco und die Arten von Sevillanas. Leitfaden zu Herkunft und Struktur.","og_url":"https:\/\/tablaoflamenco1911.com\/de\/son-las-sevillanas-un-palo-flamenco\/","og_site_name":"Tablao Flamenco 1911","article_published_time":"2026-03-31T18:56:24+00:00","article_modified_time":"2026-03-31T19:17:57+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/tablaoflamenco1911.com\/wp-content\/uploads\/2026\/03\/claudia-de-utrera-7511-scaled.webp","type":"image\/webp"}],"author":"Miguel Blanco","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Miguel Blanco","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tablaoflamenco1911.com\/es\/son-las-sevillanas-un-palo-flamenco\/#article","isPartOf":{"@id":"https:\/\/tablaoflamenco1911.com\/es\/son-las-sevillanas-un-palo-flamenco\/"},"author":{"name":"Miguel Blanco","@id":"https:\/\/tablaoflamenco1911.com\/es\/#\/schema\/person\/5c9c054f5ed0de8157b146ce7171d5e7"},"headline":"Die Sevillanas: Sind sie wirklich ein Flamenco-Stil?","datePublished":"2026-03-31T18:56:24+00:00","dateModified":"2026-03-31T19:17:57+00:00","mainEntityOfPage":{"@id":"https:\/\/tablaoflamenco1911.com\/es\/son-las-sevillanas-un-palo-flamenco\/"},"wordCount":6886,"image":{"@id":"https:\/\/tablaoflamenco1911.com\/es\/son-las-sevillanas-un-palo-flamenco\/#primaryimage"},"thumbnailUrl":"https:\/\/tablaoflamenco1911.com\/wp-content\/uploads\/2026\/03\/claudia-de-utrera-7511-scaled.webp","articleSection":["Cultura Flamenca"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/tablaoflamenco1911.com\/de\/son-las-sevillanas-un-palo-flamenco\/","url":"https:\/\/tablaoflamenco1911.com\/de\/son-las-sevillanas-un-palo-flamenco\/","name":"Sevillanas Flamenco-Stil: Sind sie Flamenco und welche Arten gibt es?","isPartOf":{"@id":"https:\/\/tablaoflamenco1911.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tablaoflamenco1911.com\/de\/son-las-sevillanas-un-palo-flamenco\/#primaryimage"},"image":{"@id":"https:\/\/tablaoflamenco1911.com\/es\/son-las-sevillanas-un-palo-flamenco\/#primaryimage"},"thumbnailUrl":"https:\/\/tablaoflamenco1911.com\/wp-content\/uploads\/2026\/03\/claudia-de-utrera-7511-scaled.webp","datePublished":"2026-03-31T18:56:24+00:00","dateModified":"2026-03-31T19:17:57+00:00","author":{"@id":"https:\/\/tablaoflamenco1911.com\/es\/#\/schema\/person\/5c9c054f5ed0de8157b146ce7171d5e7"},"description":"Erfahren Sie, ob Sevillanas ein Flamenco-Stil sind, ihre Unterschiede zum Flamenco und die Arten von Sevillanas. Leitfaden zu Herkunft und Struktur.","breadcrumb":{"@id":"https:\/\/tablaoflamenco1911.com\/de\/son-las-sevillanas-un-palo-flamenco\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/tablaoflamenco1911.com\/de\/son-las-sevillanas-un-palo-flamenco\/"]]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tablaoflamenco1911.com\/de\/son-las-sevillanas-un-palo-flamenco\/#primaryimage","url":"https:\/\/tablaoflamenco1911.com\/wp-content\/uploads\/2026\/03\/claudia-de-utrera-7511-scaled.webp","contentUrl":"https:\/\/tablaoflamenco1911.com\/wp-content\/uploads\/2026\/03\/claudia-de-utrera-7511-scaled.webp","width":2560,"height":1706,"caption":"Bailaora de flamenco con vestido rojo de lunares en el Tablao Flamenco 1911 de Madrid, representando la est\u00e9tica de las sevillanas."},{"@type":"BreadcrumbList","@id":"https:\/\/tablaoflamenco1911.com\/de\/son-las-sevillanas-un-palo-flamenco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tablaoflamenco1911.com\/de\/"},{"@type":"ListItem","position":2,"name":"Sevillanas Flamenco-Stil"}]},{"@type":"WebSite","@id":"https:\/\/tablaoflamenco1911.com\/de\/#website","url":"https:\/\/tablaoflamenco1911.com\/de\/","name":"Tablao Flamenco 1911","description":"La Catedral del Flamenco en Madrid","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tablaoflamenco1911.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/tablaoflamenco1911.com\/es\/#\/schema\/person\/5c9c054f5ed0de8157b146ce7171d5e7","name":"Miguel Blanco","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/359874fd676a9bfbf3a5d62f8bb888a22a657034662dd62c3669b5e7274a1365?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/359874fd676a9bfbf3a5d62f8bb888a22a657034662dd62c3669b5e7274a1365?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/359874fd676a9bfbf3a5d62f8bb888a22a657034662dd62c3669b5e7274a1365?s=96&d=mm&r=g","caption":"Miguel Blanco"}}]}},"_links":{"self":[{"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/posts\/54979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/comments?post=54979"}],"version-history":[{"count":2,"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/posts\/54979\/revisions"}],"predecessor-version":[{"id":54982,"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/posts\/54979\/revisions\/54982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/media\/54980"}],"wp:attachment":[{"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/media?parent=54979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/categories?post=54979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/tags?post=54979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}