{"id":54895,"date":"2026-03-12T13:24:46","date_gmt":"2026-03-12T12:24:46","guid":{"rendered":"https:\/\/tablaoflamenco1911.com\/es\/?p=54895"},"modified":"2026-04-08T13:36:11","modified_gmt":"2026-04-08T11:36:11","slug":"la-historia-del-flamenco-en-madrid","status":"publish","type":"post","link":"https:\/\/tablaoflamenco1911.com\/de\/geschichte-flamenco-madrid\/","title":{"rendered":"Die Geschichte des Flamenco in Madrid"},"content":{"rendered":"<p><\/p>\n<p data-path-to-node=\"40\">Wenn wir an die ersten Akkorde der Jondo-Kunst denken, reist der Geist automatisch nach Andalusien. Um jedoch zu verstehen, wie dieser Gesang wirklich universell wurde, muss man auf die Mitte der Landkarte schauen.<\/p>\n<p data-path-to-node=\"41\"><b data-path-to-node=\"41\" data-index-in-node=\"0\">Die Geschichte des Flamenco in Madrid ist nicht die eines einfachen Zuschauers; es ist die Geschichte der B\u00fchne, die die Gr\u00f6\u00dften katapultierte.<\/b> Zu verstehen, wie die Hauptstadt diese Kunst annahm, bedeutet zu entdecken, warum man heute nicht im Comp\u00e1s triumphieren kann, ohne vorher ihre Bretter betreten zu haben.<\/p>\n<h2 data-path-to-node=\"42\"><b data-path-to-node=\"42\" data-index-in-node=\"0\">Flamenco in Madrid: Ursprung und erste R\u00e4ume<\/b><\/h2>\n<p data-path-to-node=\"43\">Mitte des 19. Jahrhunderts brachte die Ankunft der Eisenbahn eine riesige Welle von Andalusiern in die Stadt, die mit ihren Br\u00e4uchen, ihren Gitarren und ihren Klagen auf dem R\u00fccken reisten.<\/p>\n<p data-path-to-node=\"44\"><b data-path-to-node=\"44\" data-index-in-node=\"0\">Den Ursprung des Flamenco in Madrid zu suchen, bedeutet, in die alten Corralas und die sch\u00e4bigen Tavernen<\/b> traditioneller Viertel wie Lavapi\u00e9s einzutauchen. In diesen intimen R\u00e4umen <b data-path-to-node=\"44\" data-index-in-node=\"181\">war die Kunst kein Spektakel, sie war eine Form der Erleichterung und des \u00dcberlebens.<\/b> Kurioserweise dauerte es nicht lange, bis diese rohe Kraft nicht nur die Madrider Boh\u00e8me, sondern auch die Aristokratie selbst verf\u00fchrte, die nach der Authentizit\u00e4t der Zigeunernacht zu suchen begann.<\/p>\n<h2 data-path-to-node=\"45\"><b data-path-to-node=\"45\" data-index-in-node=\"0\">Das Goldene Zeitalter des Flamenco und seine Auswirkungen auf die Hauptstadt<\/b><\/h2>\n<p data-path-to-node=\"46\"><b data-path-to-node=\"46\" data-index-in-node=\"0\">Ende des 19. und Anfang des 20. Jahrhunderts h\u00f6rte der Gesang auf, ein offenes Geheimnis zu sein. Wir treten in das sogenannte goldene Zeitalter des Flamenco ein<\/b>, eine Phase absoluter Pracht, in der die K\u00fcnstler von den Tavernen auf die beleuchteten B\u00fchnen wechselten.<\/p>\n<p data-path-to-node=\"47\">Madrid wurde zum ultimativen Magneten. <b data-path-to-node=\"47\" data-index-in-node=\"39\">Wenn man Talent hatte, musste man in die Hauptstadt kommen. Die Stadt fungierte als gigantischer Resonanzk\u00f6rper, der das wilde Talent<\/b> der K\u00fcnstler aus dem S\u00fcden polierte und ihnen das Prestige, die Vertr\u00e4ge und den Respekt verlieh, die sie brauchten, um ausschlie\u00dflich von ihrer Kunst zu leben.<\/p>\n<h2 data-path-to-node=\"48\"><b data-path-to-node=\"48\" data-index-in-node=\"0\">Der Madrider Flamenco im 20. Jahrhundert<\/b><\/h2>\n<p data-path-to-node=\"49\">Der wahre Wendepunkt kam im vergangenen Jahrhundert. <b data-path-to-node=\"49\" data-index-in-node=\"53\">Der Flamenco im Madrid des 20. Jahrhunderts ist ein Synonym f\u00fcr ewige Morgend\u00e4mmerungen und eine Industrie, die die Regeln der Musik in Spanien ver\u00e4nderte.<\/b><\/p>\n<div id=\"attachment_54896\" style=\"width: 1010px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-54896\" class=\"wp-image-54896 size-full\" src=\"https:\/\/tablaoflamenco1911.com\/wp-content\/uploads\/2026\/03\/antonio_arenas_tablaovillarosa_antiguo_escenario_en_los_60.jpeg\" alt=\"Fotograf\u00eda vintage en blanco y negro del tocaor Antonio Arenas tocando la guitarra flamenca en el centro del escenario del antiguo Tablao Villa Rosa en los a\u00f1os 60. Est\u00e1 sentado y rodeado por un cuadro flamenco de cantaores y bailaoras vestidos de \u00e9poca que le acompa\u00f1an con las palmas.\" width=\"1000\" height=\"664\" \/><p id=\"caption-attachment-54896\" class=\"wp-caption-text\">Der Meister Antonio Arenas bei einem Auftritt im alten Tablao Villa Rosa.<\/p><\/div>\n<h3 data-path-to-node=\"31\"><b data-path-to-node=\"31\" data-index-in-node=\"0\">Gesangscaf\u00e9s und erste Tablaos<\/b><\/h3>\n<p data-path-to-node=\"32\"><b data-path-to-node=\"32\" data-index-in-node=\"0\">Das Live-Format entwickelte sich weiter.<\/b> Die alten und lauten &#8222;Caf\u00e9s Cantantes&#8220; wichen den Tablaos, Veranstaltungsorten, die speziell daf\u00fcr konzipiert wurden, dem Zapateado und der Gitarre in einer fast religi\u00f6sen Stille zuzuh\u00f6ren. <b data-path-to-node=\"32\" data-index-in-node=\"232\">Diese neuen Heiligt\u00fcmer weihten die Figur des Flamenco-K\u00fcnstlers<\/b>, und trennten schlie\u00dflich die Jondo-Kunst von blo\u00dfer Hintergrundunterhaltung.<\/p>\n<h3 data-path-to-node=\"33\"><b data-path-to-node=\"33\" data-index-in-node=\"0\">Madrid als nationales und internationales Schaufenster<\/b><\/h3>\n<p data-path-to-node=\"34\"><b data-path-to-node=\"34\" data-index-in-node=\"0\">In den 50er und 60er Jahren verwandelte sich Madrid in die Welthauptstadt der Nacht.<\/b> Hollywoodstars wie Ava Gardner oder Gary Cooper, Schriftsteller, Politiker und die internationale High Society landeten in der Stadt auf der Suche nach der Leidenschaft der Tablaos. <b data-path-to-node=\"34\" data-index-in-node=\"267\">Hier, zwischen Rauch und Gitarren, bewies die Jondo-Kunst, dass sie die viszerale Kraft besa\u00df, jede Kultur zu bewegen<\/b>, und legte den Grundstein daf\u00fcr, zum <a class=\"ng-star-inserted\" href=\"https:\/\/tablaoflamenco1911.com\/de\/flamenco-unesco-kulturerbe\/\" target=\"_blank\" rel=\"noopener\">Flamenco-Weltkulturerbe<\/a> erkl\u00e4rt zu werden.<\/p>\n<h2 data-path-to-node=\"35\"><b data-path-to-node=\"35\" data-index-in-node=\"0\">Der Flamenco in Madrid heute: Tradition und Kontinuit\u00e4t<\/b><\/h2>\n<p data-path-to-node=\"36\"><b data-path-to-node=\"36\" data-index-in-node=\"0\">Heutzutage ist die Geschichte nicht stehen geblieben.<\/b> Die historischen Tablaos der Stadt bewahren weiterhin denselben Anspruch, denselben Schwei\u00df und dieselbe Reinheit, die vor Jahrzehnten die Stars anzogen. Madrid bleibt die Feuerprobe f\u00fcr jeden Vollblutk\u00fcnstler.<\/p>\n<p data-path-to-node=\"37\">\u00dcber dieses goldene Zeitalter zu lesen ist faszinierend, aber der Duende wird nicht in einem Text verstanden: Man sp\u00fcrt ihn, wenn der S\u00e4nger seine Stimme zwei Meter von einem entfernt bricht. Lassen Sie es sich nicht erz\u00e4hlen. Sp\u00fcren Sie das Gewicht dieses Erbes und kommen Sie, um es live im Tablao Flamenco 1911 zu erleben; Sie k\u00f6nnen noch heute <a class=\"ng-star-inserted\" href=\"https:\/\/tablaoflamenco1911.com\/de\/tickets-kaufen-2\/\" target=\"_blank\" rel=\"noopener\">Flamenco-Tickets kaufen<\/a> und sich Ihren Platz in der lebendigen Geschichte Madrids sichern.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"Wenn wir an die ersten Akkorde der Jondo-Kunst denken, reist der Geist automatisch nach Andalusien. Um jedoch zu verstehen, wie dieser Gesang wirklich universell wurde, muss man auf die Mitte der Landkarte schauen. Die Geschichte des Flamenco in Madrid ist nicht die eines einfachen Zuschauers; es ist die Geschichte der B\u00fchne, die die Gr\u00f6\u00dften katapultierte&#8230;.","protected":false},"author":8,"featured_media":3472,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[20],"tags":[],"class_list":["post-54895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia-del-flamenco"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Flamenco-Ursprung Madrid: Geschichte und Goldenes Zeitalter in der Hauptstadt<\/title>\n<meta name=\"description\" content=\"Entdecken Sie den Ursprung des Flamenco in Madrid, seine Rolle im Goldenen Zeitalter, den Hollywood-Glamour und die Entwicklung der Jondo-Kunst bis heute.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Flamenco-Ursprung Madrid: Geschichte und Goldenes Zeitalter in der Hauptstadt\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie den Ursprung des Flamenco in Madrid, seine Rolle im Goldenen Zeitalter, den Hollywood-Glamour und die Entwicklung der Jondo-Kunst bis heute.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tablaoflamenco1911.com\/de\/historia-flamenco-madrid\/\" \/>\n<meta property=\"og:site_name\" content=\"Tablao Flamenco 1911\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-12T12:24:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-08T11:36:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tablaoflamenco1911.com\/wp-content\/uploads\/2022\/09\/gabinete-el-quijote-sobremesa-musicos-flamencos-vino-guitarra-burdeos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Miguel Blanco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miguel Blanco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/historia-flamenco-madrid\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/historia-flamenco-madrid\\\/\"},\"author\":{\"name\":\"Miguel Blanco\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/#\\\/schema\\\/person\\\/5c9c054f5ed0de8157b146ce7171d5e7\"},\"headline\":\"Die Geschichte des Flamenco in Madrid\",\"datePublished\":\"2026-03-12T12:24:46+00:00\",\"dateModified\":\"2026-04-08T11:36:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/historia-flamenco-madrid\\\/\"},\"wordCount\":7005,\"image\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/historia-flamenco-madrid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/gabinete-el-quijote-sobremesa-musicos-flamencos-vino-guitarra-burdeos.jpg\",\"articleSection\":[\"Historia del Flamenco\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/historia-flamenco-madrid\\\/\",\"url\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/historia-flamenco-madrid\\\/\",\"name\":\"Flamenco-Ursprung Madrid: Geschichte und Goldenes Zeitalter in der Hauptstadt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/historia-flamenco-madrid\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/historia-flamenco-madrid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/gabinete-el-quijote-sobremesa-musicos-flamencos-vino-guitarra-burdeos.jpg\",\"datePublished\":\"2026-03-12T12:24:46+00:00\",\"dateModified\":\"2026-04-08T11:36:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/#\\\/schema\\\/person\\\/5c9c054f5ed0de8157b146ce7171d5e7\"},\"description\":\"Entdecken Sie den Ursprung des Flamenco in Madrid, seine Rolle im Goldenen Zeitalter, den Hollywood-Glamour und die Entwicklung der Jondo-Kunst bis heute.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/historia-flamenco-madrid\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/historia-flamenco-madrid\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/historia-flamenco-madrid\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/gabinete-el-quijote-sobremesa-musicos-flamencos-vino-guitarra-burdeos.jpg\",\"contentUrl\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/gabinete-el-quijote-sobremesa-musicos-flamencos-vino-guitarra-burdeos.jpg\",\"width\":1400,\"height\":800,\"caption\":\"Sobremesa en Gabinete el Quijote\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/historia-flamenco-madrid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Geschichte des Flamenco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/\",\"name\":\"Tablao Flamenco 1911\",\"description\":\"La Catedral del Flamenco en Madrid\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tablaoflamenco1911.com\\\/es\\\/#\\\/schema\\\/person\\\/5c9c054f5ed0de8157b146ce7171d5e7\",\"name\":\"Miguel Blanco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/359874fd676a9bfbf3a5d62f8bb888a22a657034662dd62c3669b5e7274a1365?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/359874fd676a9bfbf3a5d62f8bb888a22a657034662dd62c3669b5e7274a1365?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/359874fd676a9bfbf3a5d62f8bb888a22a657034662dd62c3669b5e7274a1365?s=96&d=mm&r=g\",\"caption\":\"Miguel Blanco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Flamenco-Ursprung Madrid: Geschichte und Goldenes Zeitalter in der Hauptstadt","description":"Entdecken Sie den Ursprung des Flamenco in Madrid, seine Rolle im Goldenen Zeitalter, den Hollywood-Glamour und die Entwicklung der Jondo-Kunst bis heute.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/","og_locale":"de_DE","og_type":"article","og_title":"Flamenco-Ursprung Madrid: Geschichte und Goldenes Zeitalter in der Hauptstadt","og_description":"Entdecken Sie den Ursprung des Flamenco in Madrid, seine Rolle im Goldenen Zeitalter, den Hollywood-Glamour und die Entwicklung der Jondo-Kunst bis heute.","og_url":"https:\/\/tablaoflamenco1911.com\/de\/historia-flamenco-madrid\/","og_site_name":"Tablao Flamenco 1911","article_published_time":"2026-03-12T12:24:46+00:00","article_modified_time":"2026-04-08T11:36:11+00:00","og_image":[{"width":1400,"height":800,"url":"https:\/\/tablaoflamenco1911.com\/wp-content\/uploads\/2022\/09\/gabinete-el-quijote-sobremesa-musicos-flamencos-vino-guitarra-burdeos.jpg","type":"image\/jpeg"}],"author":"Miguel Blanco","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Miguel Blanco","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tablaoflamenco1911.com\/es\/historia-flamenco-madrid\/#article","isPartOf":{"@id":"https:\/\/tablaoflamenco1911.com\/es\/historia-flamenco-madrid\/"},"author":{"name":"Miguel Blanco","@id":"https:\/\/tablaoflamenco1911.com\/es\/#\/schema\/person\/5c9c054f5ed0de8157b146ce7171d5e7"},"headline":"Die Geschichte des Flamenco in Madrid","datePublished":"2026-03-12T12:24:46+00:00","dateModified":"2026-04-08T11:36:11+00:00","mainEntityOfPage":{"@id":"https:\/\/tablaoflamenco1911.com\/es\/historia-flamenco-madrid\/"},"wordCount":7005,"image":{"@id":"https:\/\/tablaoflamenco1911.com\/es\/historia-flamenco-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/tablaoflamenco1911.com\/wp-content\/uploads\/2022\/09\/gabinete-el-quijote-sobremesa-musicos-flamencos-vino-guitarra-burdeos.jpg","articleSection":["Historia del Flamenco"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/tablaoflamenco1911.com\/de\/historia-flamenco-madrid\/","url":"https:\/\/tablaoflamenco1911.com\/de\/historia-flamenco-madrid\/","name":"Flamenco-Ursprung Madrid: Geschichte und Goldenes Zeitalter in der Hauptstadt","isPartOf":{"@id":"https:\/\/tablaoflamenco1911.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tablaoflamenco1911.com\/de\/historia-flamenco-madrid\/#primaryimage"},"image":{"@id":"https:\/\/tablaoflamenco1911.com\/es\/historia-flamenco-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/tablaoflamenco1911.com\/wp-content\/uploads\/2022\/09\/gabinete-el-quijote-sobremesa-musicos-flamencos-vino-guitarra-burdeos.jpg","datePublished":"2026-03-12T12:24:46+00:00","dateModified":"2026-04-08T11:36:11+00:00","author":{"@id":"https:\/\/tablaoflamenco1911.com\/es\/#\/schema\/person\/5c9c054f5ed0de8157b146ce7171d5e7"},"description":"Entdecken Sie den Ursprung des Flamenco in Madrid, seine Rolle im Goldenen Zeitalter, den Hollywood-Glamour und die Entwicklung der Jondo-Kunst bis heute.","breadcrumb":{"@id":"https:\/\/tablaoflamenco1911.com\/de\/historia-flamenco-madrid\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/tablaoflamenco1911.com\/de\/historia-flamenco-madrid\/"]]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tablaoflamenco1911.com\/de\/historia-flamenco-madrid\/#primaryimage","url":"https:\/\/tablaoflamenco1911.com\/wp-content\/uploads\/2022\/09\/gabinete-el-quijote-sobremesa-musicos-flamencos-vino-guitarra-burdeos.jpg","contentUrl":"https:\/\/tablaoflamenco1911.com\/wp-content\/uploads\/2022\/09\/gabinete-el-quijote-sobremesa-musicos-flamencos-vino-guitarra-burdeos.jpg","width":1400,"height":800,"caption":"Sobremesa en Gabinete el Quijote"},{"@type":"BreadcrumbList","@id":"https:\/\/tablaoflamenco1911.com\/de\/historia-flamenco-madrid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tablaoflamenco1911.com\/de\/"},{"@type":"ListItem","position":2,"name":"Geschichte des Flamenco"}]},{"@type":"WebSite","@id":"https:\/\/tablaoflamenco1911.com\/de\/#website","url":"https:\/\/tablaoflamenco1911.com\/de\/","name":"Tablao Flamenco 1911","description":"La Catedral del Flamenco en Madrid","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tablaoflamenco1911.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/tablaoflamenco1911.com\/es\/#\/schema\/person\/5c9c054f5ed0de8157b146ce7171d5e7","name":"Miguel Blanco","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/359874fd676a9bfbf3a5d62f8bb888a22a657034662dd62c3669b5e7274a1365?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/359874fd676a9bfbf3a5d62f8bb888a22a657034662dd62c3669b5e7274a1365?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/359874fd676a9bfbf3a5d62f8bb888a22a657034662dd62c3669b5e7274a1365?s=96&d=mm&r=g","caption":"Miguel Blanco"}}]}},"_links":{"self":[{"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/posts\/54895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/comments?post=54895"}],"version-history":[{"count":3,"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/posts\/54895\/revisions"}],"predecessor-version":[{"id":54996,"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/posts\/54895\/revisions\/54996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/media\/3472"}],"wp:attachment":[{"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/media?parent=54895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/categories?post=54895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tablaoflamenco1911.com\/de\/wp-json\/wp\/v2\/tags?post=54895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}